{"id":115555,"date":"2021-05-02T21:39:37","date_gmt":"2021-05-02T19:39:37","guid":{"rendered":"https:\/\/kimbex.pl\/samochody\/porsche-964-c2-cabrio-5-bieg-manual-super-stan\/"},"modified":"2021-05-17T17:00:39","modified_gmt":"2021-05-17T15:00:39","slug":"porsche-964-c2-cabrio-5-bieg-manual-sold","status":"publish","type":"car","link":"https:\/\/kimbex.pl\/de\/samochody\/porsche-964-c2-cabrio-5-bieg-manual-sold\/","title":{"rendered":"Porsche 964 C2 Cabrio 5 bieg manual #SOLD"},"featured_media":115473,"menu_order":0,"template":"","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Porsche 964 C2 Cabrio 5 bieg manual #SOLD | Kimbex Dream Cars<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kimbex.pl\/de\/samochody\/porsche-964-c2-cabrio-5-bieg-manual-sold\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Porsche 964 C2 Cabrio 5 bieg manual #SOLD | Kimbex Dream Cars\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kimbex.pl\/de\/samochody\/porsche-964-c2-cabrio-5-bieg-manual-sold\/\" \/>\n<meta property=\"og:site_name\" content=\"Kimbex Dream Cars\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/KimbexDreamCars\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-17T15:00:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kimbex.pl\/wp-content\/uploads\/2021\/05\/179265753_945242746277792_7947213572809086919_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Kimbex Kimbex\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kimbex.pl\/#website\",\"url\":\"https:\/\/kimbex.pl\/\",\"name\":\"Kimbex Dream Cars\",\"description\":\"Kimbex Dream Cars\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kimbex.pl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/kimbex.pl\/de\/samochody\/porsche-964-c2-cabrio-5-bieg-manual-sold\/#primaryimage\",\"url\":\"https:\/\/kimbex.pl\/wp-content\/uploads\/2021\/05\/179265753_945242746277792_7947213572809086919_n.jpg\",\"contentUrl\":\"https:\/\/kimbex.pl\/wp-content\/uploads\/2021\/05\/179265753_945242746277792_7947213572809086919_n.jpg\",\"width\":2048,\"height\":1536},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kimbex.pl\/de\/samochody\/porsche-964-c2-cabrio-5-bieg-manual-sold\/#webpage\",\"url\":\"https:\/\/kimbex.pl\/de\/samochody\/porsche-964-c2-cabrio-5-bieg-manual-sold\/\",\"name\":\"Porsche 964 C2 Cabrio 5 bieg manual #SOLD | Kimbex Dream Cars\",\"isPartOf\":{\"@id\":\"https:\/\/kimbex.pl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/kimbex.pl\/de\/samochody\/porsche-964-c2-cabrio-5-bieg-manual-sold\/#primaryimage\"},\"datePublished\":\"2021-05-02T19:39:37+00:00\",\"dateModified\":\"2021-05-17T15:00:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/kimbex.pl\/de\/samochody\/porsche-964-c2-cabrio-5-bieg-manual-sold\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kimbex.pl\/de\/samochody\/porsche-964-c2-cabrio-5-bieg-manual-sold\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kimbex.pl\/de\/samochody\/porsche-964-c2-cabrio-5-bieg-manual-sold\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/kimbex.pl\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Porsche 964 C2 Cabrio 5 bieg manual #SOLD\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Porsche 964 C2 Cabrio 5 bieg manual #SOLD | Kimbex Dream Cars","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kimbex.pl\/de\/samochody\/porsche-964-c2-cabrio-5-bieg-manual-sold\/","og_locale":"de_DE","og_type":"article","og_title":"Porsche 964 C2 Cabrio 5 bieg manual #SOLD | Kimbex Dream Cars","og_url":"https:\/\/kimbex.pl\/de\/samochody\/porsche-964-c2-cabrio-5-bieg-manual-sold\/","og_site_name":"Kimbex Dream Cars","article_publisher":"https:\/\/www.facebook.com\/KimbexDreamCars\/","article_modified_time":"2021-05-17T15:00:39+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/kimbex.pl\/wp-content\/uploads\/2021\/05\/179265753_945242746277792_7947213572809086919_n.jpg","type":"image\/jpeg"}],"author":"Kimbex Kimbex","twitter_card":"summary","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/kimbex.pl\/#website","url":"https:\/\/kimbex.pl\/","name":"Kimbex Dream Cars","description":"Kimbex Dream Cars","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kimbex.pl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/kimbex.pl\/de\/samochody\/porsche-964-c2-cabrio-5-bieg-manual-sold\/#primaryimage","url":"https:\/\/kimbex.pl\/wp-content\/uploads\/2021\/05\/179265753_945242746277792_7947213572809086919_n.jpg","contentUrl":"https:\/\/kimbex.pl\/wp-content\/uploads\/2021\/05\/179265753_945242746277792_7947213572809086919_n.jpg","width":2048,"height":1536},{"@type":"WebPage","@id":"https:\/\/kimbex.pl\/de\/samochody\/porsche-964-c2-cabrio-5-bieg-manual-sold\/#webpage","url":"https:\/\/kimbex.pl\/de\/samochody\/porsche-964-c2-cabrio-5-bieg-manual-sold\/","name":"Porsche 964 C2 Cabrio 5 bieg manual #SOLD | Kimbex Dream Cars","isPartOf":{"@id":"https:\/\/kimbex.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kimbex.pl\/de\/samochody\/porsche-964-c2-cabrio-5-bieg-manual-sold\/#primaryimage"},"datePublished":"2021-05-02T19:39:37+00:00","dateModified":"2021-05-17T15:00:39+00:00","breadcrumb":{"@id":"https:\/\/kimbex.pl\/de\/samochody\/porsche-964-c2-cabrio-5-bieg-manual-sold\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kimbex.pl\/de\/samochody\/porsche-964-c2-cabrio-5-bieg-manual-sold\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kimbex.pl\/de\/samochody\/porsche-964-c2-cabrio-5-bieg-manual-sold\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/kimbex.pl\/de\/"},{"@type":"ListItem","position":2,"name":"Porsche 964 C2 Cabrio 5 bieg manual #SOLD"}]}]}},"_links":{"self":[{"href":"https:\/\/kimbex.pl\/de\/wp-json\/wp\/v2\/car\/115555"}],"collection":[{"href":"https:\/\/kimbex.pl\/de\/wp-json\/wp\/v2\/car"}],"about":[{"href":"https:\/\/kimbex.pl\/de\/wp-json\/wp\/v2\/types\/car"}],"version-history":[{"count":3,"href":"https:\/\/kimbex.pl\/de\/wp-json\/wp\/v2\/car\/115555\/revisions"}],"predecessor-version":[{"id":121887,"href":"https:\/\/kimbex.pl\/de\/wp-json\/wp\/v2\/car\/115555\/revisions\/121887"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kimbex.pl\/de\/wp-json\/wp\/v2\/media\/115473"}],"wp:attachment":[{"href":"https:\/\/kimbex.pl\/de\/wp-json\/wp\/v2\/media?parent=115555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}